{"id":26997,"date":"2024-04-19T13:30:58","date_gmt":"2024-04-19T13:30:58","guid":{"rendered":"https:\/\/www.bouteillegpl.fr\/produit\/bombola-di-benzina-per-camper-22l-con-kit-di-rifornimento-esterno\/"},"modified":"2024-04-19T13:30:58","modified_gmt":"2024-04-19T13:30:58","slug":"bombola-di-benzina-per-camper-22l-con-kit-di-rifornimento-esterno","status":"publish","type":"product","link":"https:\/\/www.bouteillegpl.fr\/it\/produit\/bombola-di-benzina-per-camper-22l-con-kit-di-rifornimento-esterno\/","title":{"rendered":"Bombola di benzina per camper 22L con kit di rifornimento esterno"},"content":{"rendered":"<p class=\"pb-3 last:pb-0\">La bombola di gas ricaricabile CAMPKO (<strong>con kit di riempimento esterno*<\/strong>) in acciaio, con <strong>un diametro di 300<\/strong> e un&#8217;altezza<strong> di 485 mm<\/strong> (o <strong>470 mm senza protezione<\/strong>), \u00e8 conforme allo standard europeo R67.01 ed \u00e8 accompagnata da un certificato. Questa versione recente \u00e8 dotata di una polivalvola che integra una valvola da 27 bar e un indicatore di livello. <\/p>\n<p class=\"pb-3 last:pb-0\"><strong>Con una capacit\u00e0 totale di 22 litri (17 litri utilizzabili),<\/strong> \u00e8 ideale per camper, caravan, generatori o abitazioni per riscaldamento o cucina. \u00c8 possibile ricaricarlo direttamente in una stazione GPL per <strong>\u20ac0,90<\/strong> al litro. Questo cilindro pu\u00f2 essere installato nel veicolo usando un tubo e un bicchiere di riempimento (disponibili come opzione e in vendita nel nostro negozio). Una volta agganciata al veicolo, consente di rifornire la bottiglia in stazione senza dover smontare la bottiglia.   <\/p>\n<p class=\"pb-3 last:pb-0\">Hai l&#8217;opportunit\u00e0 di rifornire la tua bombola di benzina in sicurezza in qualsiasi stazione di servizio risparmiando soldi&#8230; a soli <strong>\u20ac0,90 al litro<\/strong>.<\/p>\n<p class=\"pb-3 last:pb-0\">(NESSUN TEST OBBLIGATORIO) Coppette e accessori sono disponibili come opzione. Puoi acquistarli seguendo questo link.  <\/p>\n<p><strong>*Il kit include 1 tubo Lunghezza 1 M, 1 riempimento integrato con copricerchio e tappo nero, 1 coppa di riempimento Francia Italia<\/strong><\/p>\n<p>Sui cilindri Campko, la lettura del livello GPL, che funziona a un quarto di giro, spesso manca di precisione.<br \/>\nPer una misurazione pi\u00f9 precisa e affidabile, \u00e8 fortemente consigliato collegare la bottiglia al <a href=\"https:\/\/www.bouteillegpl.fr\/produit\/jauge-bouteille-gpl-bluetooth-mopeka-campko-mo9882-e34jauge-gpl-bluetooth-pour-bouteille-alu-mo9883-e34-copie\/\"><span style=\"color: #000000;\"><strong>misuratore MOPEKA<\/strong>.<\/span><\/a> Questa soluzione innovativa ti offre una lettura accurata e in tempo reale del livello di GPL (tramite il tuo telefono cellulare o un ricevitore LED che funziona anche tramite Bluetooth), permettendoti di gestire i tuoi consumi in modo ottimale e con completa tranquillit\u00e0. <strong style=\"color: #4c00ff;\"><a style=\"color: #4c00ff;\" href=\"https:\/\/www.bouteillegpl.fr\/produit\/jauge-bouteille-gpl-bluetooth-mopeka-campko-mo9882-e34jauge-gpl-bluetooth-pour-bouteille-alu-mo9883-e34-copie\/\">Accesso a misura MOPEKA<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La bombola di benzina <strong>CAMPKO da 22L (<\/strong>17 litri utilizzabili) \u00e8 ricaricabile e progettata appositamente per i camper. Misura <strong>300 mm di diametro<\/strong> e <strong>485 mm di altezza<\/strong> (<strong>470 mm<\/strong> senza protezione). \u00c8 dotato di una nuova polivalvola che include una valvola da 27 bar, un limitatore di riempimento all&#8217;80%, una valvola di chiusura e un indicatore di livello integrato. \u00c8 certificato secondo lo standard europeo <strong>R67.01.<\/strong>   <\/p>\n<p><strong>*Il kit include 1 tubo Lunghezza 1 M, 1 riempimento integrato con copricerchio e tappo nero, 1 coppa di riempimento Francia Italia<\/strong><\/p>\n<p>Non c&#8217;\u00e8 un&#8217;ispezione obbligatoria per questa bottiglia, quindi <strong>niente nuovo test.<\/strong><\/p>\n<p>Sui cilindri Campko, la lettura del livello GPL, che funziona a un quarto di giro, spesso manca di precisione.<br \/>\nPer una misurazione pi\u00f9 precisa e affidabile, \u00e8 fortemente consigliato collegare la bottiglia al <a href=\"https:\/\/www.bouteillegpl.fr\/produit\/jauge-bouteille-gpl-bluetooth-mopeka-campko-mo9882-e34jauge-gpl-bluetooth-pour-bouteille-alu-mo9883-e34-copie\/\"><span style=\"color: #000000;\"><strong>misuratore MOPEKA<\/strong>.<\/span><\/a> Questa soluzione innovativa ti offre una lettura accurata e in tempo reale del livello di GPL (tramite il tuo telefono cellulare o un ricevitore LED che funziona anche tramite Bluetooth), permettendoti di gestire i tuoi consumi in modo ottimale e con completa tranquillit\u00e0. <strong style=\"color: #4c00ff;\"><a style=\"color: #4c00ff;\" href=\"https:\/\/www.bouteillegpl.fr\/produit\/jauge-bouteille-gpl-bluetooth-mopeka-campko-mo9882-e34jauge-gpl-bluetooth-pour-bouteille-alu-mo9883-e34-copie\/\">Accesso a misura MOPEKA<\/a><\/strong><\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"Bombola di gas GPL da 22L per camper senza collegamento CAMPKO","_seopress_titles_desc":"Bombola di gas GPL ricaricabile, marca CAMPKO. Risparmia denaro riempiendo la bottiglia di gas GPL alla stazione di servizio. ","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"ambedue","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":""},"product_brand":[],"product_cat":[503,505],"product_tag":[],"class_list":["post-26997","product","type-product","status-publish","product_cat-bombola-di-gas-gpl-ricaricabile","product_cat-campko-67r01","product_shipping_class-bottlex1","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product\/26997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/comments?post=26997"}],"version-history":[{"count":0,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product\/26997\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/media?parent=26997"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product_brand?post=26997"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product_cat?post=26997"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product_tag?post=26997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}