{"id":26580,"date":"2023-11-02T18:28:46","date_gmt":"2023-11-02T17:28:46","guid":{"rendered":"https:\/\/www.bouteillegpl.fr\/produit\/bombola-di-gas-ricaricabile-da-36l-kit-da-aperto-bout8795\/"},"modified":"2026-03-04T15:35:19","modified_gmt":"2026-03-04T14:35:19","slug":"bombola-di-gas-ricaricabile-da-36l-kit-da-aperto-bout8795","status":"publish","type":"product","link":"https:\/\/www.bouteillegpl.fr\/it\/produit\/bombola-di-gas-ricaricabile-da-36l-kit-da-aperto-bout8795\/","title":{"rendered":"Bombola di gas ricaricabile da 36L + kit da aperto BOUT8795"},"content":{"rendered":"<p>Bombola di gas RICARICABILE 36 litri 29L utile, (ACCIAIO) <strong>\u00d8300 H 685mm (o 635mm senza la protezione rimovibile con 3 viti <\/strong>) STANDARD OMOLOGATO europeo R67.01 con certificato, <strong>polivalva dotata di valvola di sicurezza<\/strong> e manometro integrato, limitatore di chiusura all&#8217;80% valvola da 27 bar, destinata a camper, caravan, bombole di gas, generatori, abitazioni per riscaldamento o uso in cucina,  ricarico diretto in una stazione di GPL a \u20ac0,90.<\/p>\n<p>Questo cilindro pu\u00f2 essere collegato al veicolo tramite un tubo e un bicchiere di rifornimento collegato consente di effettuare il rifornimento alla stazione di servizio senza dover disinstallare il cilindro. Puoi fare il pieno in qualsiasi stazione di servizio in sicurezza, risparmiando \u20ac0,90 al litro. <\/p>\n<p>(<strong>NESSUN TEST OBBLIGATORIO)<\/strong> Consegnato con tubo (1 metro) e coppa di riempimento, da fissare sulla carrozzeria del veicolo in vendita <strong><a>seguendo questo link<\/a><\/strong><\/p>\n<p>Sui cilindri Campko, la lettura del livello GPL, che funziona a un quarto di giro, spesso manca di precisione.<br \/>\nPer una misurazione pi\u00f9 precisa e affidabile, \u00e8 fortemente consigliato collegare la bottiglia al <a href=\"https:\/\/www.bouteillegpl.fr\/it\/produit\/mopeka-campko-bluetooth-lpg-bottle-gauge-mo9882-e34\/\"><span style=\"color: #000000;\"><strong>misuratore MOPEKA<\/strong>.<\/span><\/a> Questa soluzione innovativa ti offre una lettura accurata e in tempo reale del livello di GPL (tramite il tuo telefono cellulare o un ricevitore LED che funziona anche tramite Bluetooth), permettendoti di gestire i tuoi consumi in modo ottimale e con completa tranquillit\u00e0. <strong style=\"color: #4c00ff;\"><a style=\"color: #4c00ff;\" href=\"https:\/\/www.bouteillegpl.fr\/it\/produit\/mopeka-campko-bluetooth-lpg-bottle-gauge-mo9882-e34\/\">Accesso a misura MOPEKA<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOMBOLA DI GAS RICARICABILE CAMPKO (ACCIAIO) 36L (29L utilizzabili) <strong>\u00d8300 H 685mm<\/strong> <strong>(635mm senza protezione<\/strong>)<\/p>\n<p>Limitatore di riempimento all&#8217;80%, valvola 27BARS con presa + manometro integrato, <strong>APPROVATO<\/strong> con <strong>certificato standard europeo R67.01<\/strong><\/p>\n<p>Consegnato con coppa di rifornimento tubo (1M) da fissare sulla carrozzeria del veicolo + coppa francese \u00d822<\/p>\n<p><strong>(NESSUN TEST OBBLIGATORIO) Riempimento diretto in una<br \/>\nstazione di GPL Sui cilindri di Campko, la lettura del livello di GPL, che funziona a un quarto di giro, spesso manca di precisione.<br \/>\nPer una misurazione pi\u00f9 precisa e affidabile, \u00e8 fortemente consigliato collegare la bottiglia al <a href=\"https:\/\/www.bouteillegpl.fr\/it\/produit\/mopeka-campko-bluetooth-lpg-bottle-gauge-mo9882-e34\/\"><span style=\"color: #000000;\">misuratore MOPEKA.<\/span><\/a> Questa soluzione innovativa ti offre una lettura accurata e in tempo reale del livello di GPL (tramite il tuo telefono cellulare o un ricevitore LED che funziona anche tramite Bluetooth), permettendoti di gestire i tuoi consumi in modo ottimale e con completa tranquillit\u00e0. <strong style=\"color: #4c00ff;\"><a style=\"color: #4c00ff;\" href=\"https:\/\/www.bouteillegpl.fr\/it\/produit\/mopeka-campko-bluetooth-lpg-bottle-gauge-mo9882-e34\/\">Accesso a misura MOPEKA<\/a><\/strong><br \/>\n<\/strong><\/p>\n","protected":false},"featured_media":26543,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"Miglior bombola di gas ricaricabile da 36L con connetta e presa","_seopress_titles_desc":"Bombola di gas GPL ricaricabile (36L). Molto pratico, economico. Questa bottiglia \u00e8 la pi\u00f9 sicura sul mercato in Europa. Venduto con tutti i raccordi di riempimento. Pronto all'uso.    ","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"ambedue","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":""},"product_brand":[],"product_cat":[503,505],"product_tag":[],"class_list":["post-26580","product","type-product","status-publish","has-post-thumbnail","product_cat-bombola-di-gas-gpl-ricaricabile","product_cat-campko-67r01","product_shipping_class-bottlex1","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product\/26580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/comments?post=26580"}],"version-history":[{"count":2,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product\/26580\/revisions"}],"predecessor-version":[{"id":28619,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product\/26580\/revisions\/28619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/media\/26543"}],"wp:attachment":[{"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/media?parent=26580"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product_brand?post=26580"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product_cat?post=26580"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bouteillegpl.fr\/it\/wp-json\/wp\/v2\/product_tag?post=26580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}